{"id":4882,"date":"2026-06-26T12:00:49","date_gmt":"2026-06-26T12:00:49","guid":{"rendered":"https:\/\/yes-luxdrinx.com\/?p=4882"},"modified":"2026-07-10T08:57:02","modified_gmt":"2026-07-10T08:57:02","slug":"classic-yes-spritz","status":"publish","type":"post","link":"https:\/\/yes-luxdrinx.com\/en\/classic-yes-spritz\/","title":{"rendered":"Classic YES Spritz"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4882\" class=\"elementor elementor-4882 elementor-2934\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5428889 e-con-full e-flex e-con e-parent\" data-id=\"5428889\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-90cfa49 elementor-widget elementor-widget-heading\" data-id=\"90cfa49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The timeless Italian aperitif \u2013 slightly bitter, pleasantly sparkling, and perfect for sunny afternoons or warm summer evenings.\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b5d878 elementor-widget elementor-widget-heading\" data-id=\"4b5d878\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ingredients<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e922049 elementor-widget elementor-widget-text-editor\" data-id=\"e922049\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li>6 cl YES Spritz<\/li><li>9 cl Prosecco<\/li><li>3 cl soda water<\/li><li>Ice cubes<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67586bf elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"67586bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f54381f elementor-widget elementor-widget-heading\" data-id=\"f54381f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Garnish<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6bd4a98 elementor-widget elementor-widget-text-editor\" data-id=\"6bd4a98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li>Orange slice<\/li><li>Orange zest (optional)<\/li><li>Green olive (optional, for a modern Mediterranean touch)<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e396e33 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e396e33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0e9cc0 elementor-widget elementor-widget-heading\" data-id=\"f0e9cc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Preparation<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8039e37 elementor-widget elementor-widget-text-editor\" data-id=\"8039e37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li data-section-id=\"ubnq11\" data-start=\"398\" data-end=\"453\">Fill a large wine glass generously with ice cubes.<\/li><li data-section-id=\"ubnq11\" data-start=\"398\" data-end=\"453\">Pour in the YES Spritz.<\/li><li data-section-id=\"ubnq11\" data-start=\"398\" data-end=\"453\">Top up with well-chilled Prosecco.<\/li><li data-section-id=\"ubnq11\" data-start=\"398\" data-end=\"453\">Add a splash of soda water.<\/li><li data-section-id=\"ubnq11\" data-start=\"398\" data-end=\"453\">Stir gently to preserve the carbonation.<\/li><li data-section-id=\"ubnq11\" data-start=\"398\" data-end=\"453\">Garnish with a fresh orange slice and optionally an orange zest or a small olive sprig.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2d9e7b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e2d9e7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c58ecff elementor-widget elementor-widget-heading\" data-id=\"c58ecff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Flavor profile<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8701d9d elementor-widget elementor-widget-text-editor\" data-id=\"8701d9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Fruity \u2022 bittersweet \u2022 sparkling \u2022 Mediterranean<\/p><p>The delicate orange and herbal notes of YES Spritz combine harmoniously with the elegant bubbles of Prosecco. The soda adds extra freshness and makes the cocktail pleasantly light.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b91bb56 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b91bb56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e485fe1 elementor-widget elementor-widget-heading\" data-id=\"e485fe1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Enjoy your drink<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>The timeless Italian aperitif \u2013 slightly bitter, pleasantly sparkling, and perfect for sunny afternoons or warm summer evenings.<\/p>\n","protected":false},"author":1,"featured_media":4881,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[],"class_list":["post-4882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-yes-spritz"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Classic YES Spritz - Yes Drinx<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/yes-luxdrinx.com\/en\/classic-yes-spritz\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Classic YES Spritz - Yes Drinx\" \/>\n<meta property=\"og:description\" content=\"The timeless Italian aperitif \u2013 slightly bitter, pleasantly sparkling, and perfect for sunny afternoons or warm summer evenings.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/yes-luxdrinx.com\/en\/classic-yes-spritz\/\" \/>\n<meta property=\"og:site_name\" content=\"Yes Drinx\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-26T12:00:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T08:57:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/yes-luxdrinx.com\/wp-content\/uploads\/2026\/06\/yes-spritz-classic.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1537\" \/>\n\t<meta property=\"og:image:height\" content=\"1023\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/yes-luxdrinx.com\\\/en\\\/classic-yes-spritz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/yes-luxdrinx.com\\\/en\\\/classic-yes-spritz\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/yes-luxdrinx.com\\\/#\\\/schema\\\/person\\\/d34d3fb37f75dde96edf82b05b7efd5a\"},\"headline\":\"Classic YES Spritz\",\"datePublished\":\"2026-06-26T12:00:49+00:00\",\"dateModified\":\"2026-07-10T08:57:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/yes-luxdrinx.com\\\/en\\\/classic-yes-spritz\\\/\"},\"wordCount\":130,\"image\":{\"@id\":\"https:\\\/\\\/yes-luxdrinx.com\\\/en\\\/classic-yes-spritz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/yes-luxdrinx.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/yes-spritz-classic.jpg\",\"articleSection\":[\"Yes Spritz\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/yes-luxdrinx.com\\\/en\\\/classic-yes-spritz\\\/\",\"url\":\"https:\\\/\\\/yes-luxdrinx.com\\\/en\\\/classic-yes-spritz\\\/\",\"name\":\"Classic YES Spritz - Yes Drinx\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/yes-luxdrinx.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/yes-luxdrinx.com\\\/en\\\/classic-yes-spritz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/yes-luxdrinx.com\\\/en\\\/classic-yes-spritz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/yes-luxdrinx.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/yes-spritz-classic.jpg\",\"datePublished\":\"2026-06-26T12:00:49+00:00\",\"dateModified\":\"2026-07-10T08:57:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/yes-luxdrinx.com\\\/#\\\/schema\\\/person\\\/d34d3fb37f75dde96edf82b05b7efd5a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/yes-luxdrinx.com\\\/en\\\/classic-yes-spritz\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/yes-luxdrinx.com\\\/en\\\/classic-yes-spritz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/yes-luxdrinx.com\\\/en\\\/classic-yes-spritz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/yes-luxdrinx.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/yes-spritz-classic.jpg\",\"contentUrl\":\"https:\\\/\\\/yes-luxdrinx.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/yes-spritz-classic.jpg\",\"width\":1537,\"height\":1023},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/yes-luxdrinx.com\\\/en\\\/classic-yes-spritz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/yes-luxdrinx.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Classic YES Spritz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/yes-luxdrinx.com\\\/#website\",\"url\":\"https:\\\/\\\/yes-luxdrinx.com\\\/\",\"name\":\"Yes Drinx\",\"description\":\"Premium drinx from Luxembourg\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/yes-luxdrinx.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/yes-luxdrinx.com\\\/#\\\/schema\\\/person\\\/d34d3fb37f75dde96edf82b05b7efd5a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6fac7e5370deac9f4d92fb762897912ff89fdd1c8a6c4b34ac088f71fcdebcac?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6fac7e5370deac9f4d92fb762897912ff89fdd1c8a6c4b34ac088f71fcdebcac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6fac7e5370deac9f4d92fb762897912ff89fdd1c8a6c4b34ac088f71fcdebcac?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/yes-luxdrinx.com\"],\"url\":\"https:\\\/\\\/yes-luxdrinx.com\\\/en\\\/author\\\/info_0rzqnkgx\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Classic YES Spritz - Yes Drinx","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/yes-luxdrinx.com\/en\/classic-yes-spritz\/","og_locale":"en_US","og_type":"article","og_title":"Classic YES Spritz - Yes Drinx","og_description":"The timeless Italian aperitif \u2013 slightly bitter, pleasantly sparkling, and perfect for sunny afternoons or warm summer evenings.","og_url":"https:\/\/yes-luxdrinx.com\/en\/classic-yes-spritz\/","og_site_name":"Yes Drinx","article_published_time":"2026-06-26T12:00:49+00:00","article_modified_time":"2026-07-10T08:57:02+00:00","og_image":[{"width":1537,"height":1023,"url":"https:\/\/yes-luxdrinx.com\/wp-content\/uploads\/2026\/06\/yes-spritz-classic.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/yes-luxdrinx.com\/en\/classic-yes-spritz\/#article","isPartOf":{"@id":"https:\/\/yes-luxdrinx.com\/en\/classic-yes-spritz\/"},"author":{"name":"admin","@id":"https:\/\/yes-luxdrinx.com\/#\/schema\/person\/d34d3fb37f75dde96edf82b05b7efd5a"},"headline":"Classic YES Spritz","datePublished":"2026-06-26T12:00:49+00:00","dateModified":"2026-07-10T08:57:02+00:00","mainEntityOfPage":{"@id":"https:\/\/yes-luxdrinx.com\/en\/classic-yes-spritz\/"},"wordCount":130,"image":{"@id":"https:\/\/yes-luxdrinx.com\/en\/classic-yes-spritz\/#primaryimage"},"thumbnailUrl":"https:\/\/yes-luxdrinx.com\/wp-content\/uploads\/2026\/06\/yes-spritz-classic.jpg","articleSection":["Yes Spritz"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/yes-luxdrinx.com\/en\/classic-yes-spritz\/","url":"https:\/\/yes-luxdrinx.com\/en\/classic-yes-spritz\/","name":"Classic YES Spritz - Yes Drinx","isPartOf":{"@id":"https:\/\/yes-luxdrinx.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/yes-luxdrinx.com\/en\/classic-yes-spritz\/#primaryimage"},"image":{"@id":"https:\/\/yes-luxdrinx.com\/en\/classic-yes-spritz\/#primaryimage"},"thumbnailUrl":"https:\/\/yes-luxdrinx.com\/wp-content\/uploads\/2026\/06\/yes-spritz-classic.jpg","datePublished":"2026-06-26T12:00:49+00:00","dateModified":"2026-07-10T08:57:02+00:00","author":{"@id":"https:\/\/yes-luxdrinx.com\/#\/schema\/person\/d34d3fb37f75dde96edf82b05b7efd5a"},"breadcrumb":{"@id":"https:\/\/yes-luxdrinx.com\/en\/classic-yes-spritz\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/yes-luxdrinx.com\/en\/classic-yes-spritz\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/yes-luxdrinx.com\/en\/classic-yes-spritz\/#primaryimage","url":"https:\/\/yes-luxdrinx.com\/wp-content\/uploads\/2026\/06\/yes-spritz-classic.jpg","contentUrl":"https:\/\/yes-luxdrinx.com\/wp-content\/uploads\/2026\/06\/yes-spritz-classic.jpg","width":1537,"height":1023},{"@type":"BreadcrumbList","@id":"https:\/\/yes-luxdrinx.com\/en\/classic-yes-spritz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/yes-luxdrinx.com\/"},{"@type":"ListItem","position":2,"name":"Classic YES Spritz"}]},{"@type":"WebSite","@id":"https:\/\/yes-luxdrinx.com\/#website","url":"https:\/\/yes-luxdrinx.com\/","name":"Yes Drinx","description":"Premium drinx from Luxembourg","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/yes-luxdrinx.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/yes-luxdrinx.com\/#\/schema\/person\/d34d3fb37f75dde96edf82b05b7efd5a","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/6fac7e5370deac9f4d92fb762897912ff89fdd1c8a6c4b34ac088f71fcdebcac?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6fac7e5370deac9f4d92fb762897912ff89fdd1c8a6c4b34ac088f71fcdebcac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6fac7e5370deac9f4d92fb762897912ff89fdd1c8a6c4b34ac088f71fcdebcac?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/yes-luxdrinx.com"],"url":"https:\/\/yes-luxdrinx.com\/en\/author\/info_0rzqnkgx\/"}]}},"_links":{"self":[{"href":"https:\/\/yes-luxdrinx.com\/en\/wp-json\/wp\/v2\/posts\/4882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yes-luxdrinx.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yes-luxdrinx.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yes-luxdrinx.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/yes-luxdrinx.com\/en\/wp-json\/wp\/v2\/comments?post=4882"}],"version-history":[{"count":4,"href":"https:\/\/yes-luxdrinx.com\/en\/wp-json\/wp\/v2\/posts\/4882\/revisions"}],"predecessor-version":[{"id":4886,"href":"https:\/\/yes-luxdrinx.com\/en\/wp-json\/wp\/v2\/posts\/4882\/revisions\/4886"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yes-luxdrinx.com\/en\/wp-json\/wp\/v2\/media\/4881"}],"wp:attachment":[{"href":"https:\/\/yes-luxdrinx.com\/en\/wp-json\/wp\/v2\/media?parent=4882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yes-luxdrinx.com\/en\/wp-json\/wp\/v2\/categories?post=4882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yes-luxdrinx.com\/en\/wp-json\/wp\/v2\/tags?post=4882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}